{"id":1387,"date":"2023-04-14T20:25:39","date_gmt":"2023-04-14T20:25:39","guid":{"rendered":"http:\/\/hollylodz.com\/?page_id=1387"},"modified":"2026-04-25T13:12:44","modified_gmt":"2026-04-25T13:12:44","slug":"przygotowanie-umow-i-negocjacje","status":"publish","type":"page","link":"https:\/\/hollylodz.com\/index.php\/przygotowanie-umow-i-negocjacje\/","title":{"rendered":"Przygotowanie um\u00f3w i negocjacje"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1387\" class=\"elementor elementor-1387\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84921ab elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"84921ab\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c378b71\" data-id=\"2c378b71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31e2f5b6 elementor-widget__width-inherit elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"31e2f5b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_mobile\"\n\t\t\tdata-hamburger-icon=\"\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"767\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                                    <span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span>\n                            <\/button>\n            <div id=\"ekit-megamenu-menu\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-menu\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-1783\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1783 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/\" class=\"ekit-menu-nav-link\">Home<\/a><\/li>\n<li id=\"menu-item-4070\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-4070 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/filmproduct.com\/\" class=\"ekit-menu-nav-link\" target=\"_blank\" rel=\"noopener\">System FPMS<\/a><\/li>\n<li id=\"menu-item-1782\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1782 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/uslugi-filmowe\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Us\u0142ugi<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-3879\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3879 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/prowadzenie-biura-produkcji-filmowych\/\" class=\" dropdown-item\">Prowadzenie biura dla realizacji produkcji filmowych<\/a>\t<li id=\"menu-item-3885\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3885 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/wynajem-nieruchomosci\/\" class=\" dropdown-item\">Wynajem nieruchomo\u015bci do zdj\u0119\u0107<\/a>\t<li id=\"menu-item-3884\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3884 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/uslugi-prawne-2\/\" class=\" dropdown-item\">Us\u0142ugi prawne<\/a>\t<li id=\"menu-item-3880\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3880 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/przygotowanie-umow-i-negocjacje\/\" class=\" dropdown-item\">Przygotowanie um\u00f3w i negocjacje<\/a>\t<li id=\"menu-item-3881\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3881 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/ubezpieczenia\/\" class=\" dropdown-item\">Ubezpieczenia<\/a>\t<li id=\"menu-item-3878\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3878 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/organizacja-kostiumow-i-ubran\/\" class=\" dropdown-item\">Organizacja kostium\u00f3w i ubra\u0144<\/a>\t<li id=\"menu-item-3899\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3899 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/wynajem-sprzetu\/\" class=\" dropdown-item\">Wynajem sprz\u0119tu filmowego<\/a>\t<li id=\"menu-item-3900\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3900 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/wynajem-samochodow-i-pojazdow-specjalnych\/\" class=\" dropdown-item\">Wynajem samochod\u00f3w i pojazd\u00f3w specjalnych<\/a>\t<li id=\"menu-item-3882\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3882 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/uslugi-cateringowe-dla-ekip-filmowych\/\" class=\" dropdown-item\">Us\u0142ugi cateringowe dla ekip filmowych<\/a>\t<li id=\"menu-item-3901\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3901 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/17\/montaz-filmu\/\" class=\" dropdown-item\">Monta\u017c filmu<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-3939\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-3939 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/kierownictwo-produkcji\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Produkcja Filmowa<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-3876\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3876 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/development\/\" class=\" dropdown-item\">Development Film\u00f3w<\/a>\t<li id=\"menu-item-3877\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3877 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/fundusze-filmowe-dofinansowania-na-film\/\" class=\" dropdown-item\">Fundusze, Dofinansowania, Dotacje<\/a>\t<li id=\"menu-item-3896\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3896 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/17\/dofinansowanie-pisf\/\" class=\" dropdown-item\">Dotacje PISF<\/a>\t<li id=\"menu-item-3898\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3898 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/fundusze-filmowe-dofinansowania-na-film\/sponsorzy\/\" class=\" dropdown-item\">Sponsorzy<\/a>\t<li id=\"menu-item-3875\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3875 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/produkcja\/\" class=\" dropdown-item\">Okres zdj\u0119ciowy<\/a>\t<li id=\"menu-item-3874\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3874 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/postprodukcja\/\" class=\" dropdown-item\">Postprodukcja<\/a>\t<li id=\"menu-item-3873\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3873 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/dystrybucja\/\" class=\" dropdown-item\">Dystrybucja<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-1779\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1779 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/blog-filmowy\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Blog<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-3894\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3894 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/21\/premiery-filmowe\/\" class=\" dropdown-item\">Premiery filmowe<\/a>\t<li id=\"menu-item-3895\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3895 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/17\/nagrody-i-festiwale-filmowe\/\" class=\" dropdown-item\">Nagrody i festiwale filmowe<\/a>\t<li id=\"menu-item-3891\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3891 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/07\/top-10-polskich-rezyserow\/\" class=\" dropdown-item\">TOP 10 polskich re\u017cyser\u00f3w<\/a>\t<li id=\"menu-item-3892\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3892 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/07\/top-10-polskich-aktorow\/\" class=\" dropdown-item\">TOP 10 polskich aktor\u00f3w<\/a>\t<li id=\"menu-item-3893\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3893 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/27\/top-10-polskich-aktorek\/\" class=\" dropdown-item\">TOP 10 polskich aktorek<\/a>\t<li id=\"menu-item-3889\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3889 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/08\/top-10-polskich-operatorow-filmowych\/\" class=\" dropdown-item\">TOP 10 polskich operator\u00f3w filmowych<\/a>\t<li id=\"menu-item-3888\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3888 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/08\/top-10-polskich-producentow-filmowych-2\/\" class=\" dropdown-item\">TOP 10 polskich producent\u00f3w filmowych<\/a>\t<li id=\"menu-item-3890\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3890 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/07\/top-10-polskich-kompozytorow\/\" class=\" dropdown-item\">TOP 10 polskich kompozytor\u00f3w<\/a>\t<li id=\"menu-item-3887\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3887 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/08\/top-10-polskich-scenarzystow-filmowych\/\" class=\" dropdown-item\">TOP 10 polskich scenarzyst\u00f3w filmowych<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-1780\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1780 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/kontakt\/\" class=\"ekit-menu-nav-link\">Kontakt<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13a36e05 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"13a36e05\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-540ee629\" data-id=\"540ee629\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-926fd26\" data-id=\"926fd26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-544aaef6 animated-slow elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"544aaef6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Przygotowanie um\u00f3w i negocjacje<\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71abdd7e elementor-widget elementor-widget-elementskit-heading\" data-id=\"71abdd7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"elementskit-section-subtitle  \">\n\t\t\t\t\t\tFilm production agency\n\t\t\t\t\t<\/h2><h2 class=\"ekit-heading--title elementskit-section-title \">Pomo\u017cemy tobie z tym<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a0e875f\" data-id=\"a0e875f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1278193d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1278193d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71df7ea0\" data-id=\"71df7ea0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54da4f9a elementor-widget elementor-widget-heading\" data-id=\"54da4f9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O naszej us\u0142udze<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-711124b7 elementor-widget elementor-widget-elementskit-heading\" data-id=\"711124b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper center   ekit_heading_tablet-   ekit_heading_mobile-\"><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Pomagamy producentom filmowym w negocjacjach i przygotowaniu um\u00f3w z r\u00f3\u017cnymi podmiotami zwi\u0105zanymi z produkcj\u0105 filmow\u0105. Zazwyczaj w sk\u0142ad us\u0142ugi wchodzi przygotowanie um\u00f3w z aktorami, re\u017cyserami, scenarzystami, zespo\u0142em technicznym, dystrybutorami, partnerami marketingowymi i innymi podmiotami.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e93c064 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7e93c064\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1b38b704\" data-id=\"1b38b704\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a6b630e elementor-widget elementor-widget-text-editor\" data-id=\"1a6b630e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Przygotowanie um\u00f3w i negocjacje obejmuj\u0105 ustalanie warunk\u00f3w um\u00f3w, takich jak wynagrodzenie, warunki wykorzystania dzie\u0142a, prawa autorskie, czas trwania umowy, klauzule ochronne i inne kwestie zwi\u0105zane z konkretn\u0105 umow\u0105. Doradcy prawni dla produkcji filmowej pomagaj\u0105 r\u00f3wnie\u017c w negocjacjach z r\u00f3\u017cnymi podmiotami, dbaj\u0105c o to, \u017ceby interesy producent\u00f3w by\u0142y chronione i umowy by\u0142y korzystne dla wszystkich stron.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37c1288e\" data-id=\"37c1288e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-737e8861 elementor-widget elementor-widget-image\" data-id=\"737e8861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"511\" src=\"https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/document-agreement-documents-428334-768x511.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1559\" alt=\"document, agreement, documents-428334.jpg\" srcset=\"https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/document-agreement-documents-428334-768x511.jpg 768w, https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/document-agreement-documents-428334-300x199.jpg 300w, https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/document-agreement-documents-428334-1024x681.jpg 1024w, https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/document-agreement-documents-428334.jpg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30e36d43 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"30e36d43\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6648ac62\" data-id=\"6648ac62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-412b01c2 elementor-widget elementor-widget-image\" data-id=\"412b01c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"512\" data-src=\"https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/mayor-signature-sign-917149-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1560 lazyload\" alt=\"mayor, signature, sign-917149.jpg\" data-srcset=\"https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/mayor-signature-sign-917149-768x512.jpg 768w, https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/mayor-signature-sign-917149-300x200.jpg 300w, https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/mayor-signature-sign-917149-1024x682.jpg 1024w, https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/04\/mayor-signature-sign-917149.jpg 1280w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/512;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-36b8b1e9\" data-id=\"36b8b1e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54cfe6c5 elementor-widget elementor-widget-text-editor\" data-id=\"54cfe6c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Us\u0142uga przygotowania um\u00f3w i negocjacji dla produkcji filmowej jest kluczowa dla producent\u00f3w filmowych, poniewa\u017c umowy s\u0105 jednym z najwa\u017cniejszych element\u00f3w produkcji filmowej. Korzystne i profesjonalne umowy z zapewnieniem w\u0142a\u015bciwych zabezpiecze\u0144 prawnych s\u0105 kluczowe dla sukcesu projektu filmowego. Dzi\u0119ki pomocy prawnik\u00f3w, producenci filmowi mog\u0105 mie\u0107 pewno\u015b\u0107, \u017ce umowy s\u0105 dobrze przygotowane i negocjowane, a ich interesy s\u0105 chronione.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-738ae1fd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"738ae1fd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29e3aa55\" data-id=\"29e3aa55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1df9ebb1 elementor-widget elementor-widget-heading\" data-id=\"1df9ebb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dowiedz si\u0119 wi\u0119cej<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b9e21a5 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4b9e21a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zapraszamy do kontaktu<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dafe521\" data-id=\"dafe521\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-300101e7 wpr-button-icon-style-inline wpr-button-icon-position-right elementor-invisible elementor-widget elementor-widget-wpr-button\" data-id=\"300101e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"wpr-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t\t\n\t\t\n\t\t<div class=\"wpr-button-wrap elementor-clearfix\">\n\t\t<a class=\"wpr-button wpr-button-effect elementor-animation-grow\" data-text=\"\" href=\"https:\/\/hollylodz.com\/index.php\/kontakt\/\">\n\t\t\t\n\t\t\t<span class=\"wpr-button-content\">\n\t\t\t\t\t\t\t\t\t<span class=\"wpr-button-text\">Skontaktuj si\u0119<\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99a27b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"99a27b8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7c9cffb\" data-id=\"7c9cffb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cdd072 elementor-widget elementor-widget-elementskit-heading\" data-id=\"0cdd072\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-text_center\"><p class=\"ekit-heading--title elementskit-section-title \">\u00a92023 HollyLodz.com<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a26ff5a\" data-id=\"a26ff5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-582ed7e elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-elementskit-page-list\" data-id=\"582ed7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-page-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"elementor-icon-list-items  elementor-inline-items\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-050c974 ekit_badge_left\" href=\"https:\/\/hollylodz.com\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Strona g\u0142\u00f3wna<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-29e6080 ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/blog-filmowy\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Blog<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-5b06c44 ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/ekipy-filmowe\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Ekipy Filmowe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-2c96bcf ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/uslugi-filmowe\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Oferta<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-7739305 ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/kontakt\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Kontakt<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-64b7ccf ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/mapastrony\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Mapa<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a0 Home Oferta Produkcja Ekipy Filmowe Blog Mapa Kontakt X Przygotowanie um\u00f3w i negocjacje Film production agency Pomo\u017cemy tobie z tym O naszej us\u0142udze Pomagamy producentom filmowym w negocjacjach i przygotowaniu um\u00f3w z r\u00f3\u017cnymi podmiotami zwi\u0105zanymi z produkcj\u0105 filmow\u0105. Zazwyczaj w sk\u0142ad us\u0142ugi wchodzi przygotowanie um\u00f3w z aktorami, re\u017cyserami, scenarzystami, zespo\u0142em technicznym, dystrybutorami, partnerami marketingowymi i innymi podmiotami. Przygotowanie um\u00f3w i negocjacje obejmuj\u0105 ustalanie warunk\u00f3w um\u00f3w, takich jak wynagrodzenie, warunki wykorzystania dzie\u0142a, prawa autorskie, czas trwania umowy, klauzule ochronne i inne kwestie zwi\u0105zane z konkretn\u0105 umow\u0105. Doradcy prawni dla produkcji filmowej pomagaj\u0105 r\u00f3wnie\u017c w negocjacjach z r\u00f3\u017cnymi podmiotami, dbaj\u0105c o to, \u017ceby interesy producent\u00f3w by\u0142y chronione i umowy by\u0142y korzystne dla wszystkich stron. Us\u0142uga przygotowania um\u00f3w i negocjacji dla produkcji filmowej jest kluczowa dla producent\u00f3w filmowych, poniewa\u017c umowy s\u0105 jednym z najwa\u017cniejszych element\u00f3w produkcji filmowej. Korzystne i profesjonalne umowy z zapewnieniem w\u0142a\u015bciwych zabezpiecze\u0144 prawnych s\u0105 kluczowe dla sukcesu projektu filmowego. Dzi\u0119ki pomocy prawnik\u00f3w, producenci filmowi mog\u0105 mie\u0107 pewno\u015b\u0107, \u017ce umowy s\u0105 dobrze przygotowane i negocjowane, a ich interesy s\u0105 chronione. Dowiedz si\u0119 wi\u0119cej Zapraszamy do kontaktu Skontaktuj si\u0119 \u00a92023 HollyLodz.com Strona g\u0142\u00f3wna Blog Ekipy Filmowe Oferta Kontakt Mapa<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-1387","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/pages\/1387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/comments?post=1387"}],"version-history":[{"count":13,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/pages\/1387\/revisions"}],"predecessor-version":[{"id":3701,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/pages\/1387\/revisions\/3701"}],"wp:attachment":[{"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/media?parent=1387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}