{"id":2124,"date":"2023-04-17T12:50:28","date_gmt":"2023-04-17T12:50:28","guid":{"rendered":"http:\/\/hollylodz.com\/?p=2124"},"modified":"2023-05-19T15:10:45","modified_gmt":"2023-05-19T15:10:45","slug":"ekipa-filmowa","status":"publish","type":"post","link":"https:\/\/hollylodz.com\/index.php\/2023\/04\/17\/ekipa-filmowa\/","title":{"rendered":"Ekipa filmowa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2124\" class=\"elementor elementor-2124\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3745254b elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3745254b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4907d5fc\" data-id=\"4907d5fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74f9a418 elementor-widget__width-inherit elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"74f9a418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_mobile\"\n\t\t\tdata-hamburger-icon=\"\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"767\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                                    <span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span>\n                            <\/button>\n            <div id=\"ekit-megamenu-menu\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-menu\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-1783\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1783 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/\" class=\"ekit-menu-nav-link\">Home<\/a><\/li>\n<li id=\"menu-item-4070\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-4070 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/filmproduct.com\/\" class=\"ekit-menu-nav-link\" target=\"_blank\" rel=\"noopener\">System FPMS<\/a><\/li>\n<li id=\"menu-item-1782\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1782 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/uslugi-filmowe\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Us\u0142ugi<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-3879\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3879 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/prowadzenie-biura-produkcji-filmowych\/\" class=\" dropdown-item\">Prowadzenie biura dla realizacji produkcji filmowych<\/a>\t<li id=\"menu-item-3885\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3885 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/wynajem-nieruchomosci\/\" class=\" dropdown-item\">Wynajem nieruchomo\u015bci do zdj\u0119\u0107<\/a>\t<li id=\"menu-item-3884\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3884 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/uslugi-prawne-2\/\" class=\" dropdown-item\">Us\u0142ugi prawne<\/a>\t<li id=\"menu-item-3880\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3880 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/przygotowanie-umow-i-negocjacje\/\" class=\" dropdown-item\">Przygotowanie um\u00f3w i negocjacje<\/a>\t<li id=\"menu-item-3881\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3881 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/ubezpieczenia\/\" class=\" dropdown-item\">Ubezpieczenia<\/a>\t<li id=\"menu-item-3878\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3878 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/organizacja-kostiumow-i-ubran\/\" class=\" dropdown-item\">Organizacja kostium\u00f3w i ubra\u0144<\/a>\t<li id=\"menu-item-3899\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3899 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/wynajem-sprzetu\/\" class=\" dropdown-item\">Wynajem sprz\u0119tu filmowego<\/a>\t<li id=\"menu-item-3900\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3900 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/wynajem-samochodow-i-pojazdow-specjalnych\/\" class=\" dropdown-item\">Wynajem samochod\u00f3w i pojazd\u00f3w specjalnych<\/a>\t<li id=\"menu-item-3882\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3882 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/uslugi-cateringowe-dla-ekip-filmowych\/\" class=\" dropdown-item\">Us\u0142ugi cateringowe dla ekip filmowych<\/a>\t<li id=\"menu-item-3901\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3901 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/17\/montaz-filmu\/\" class=\" dropdown-item\">Monta\u017c filmu<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-3939\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-3939 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/kierownictwo-produkcji\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Produkcja Filmowa<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-3876\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3876 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/development\/\" class=\" dropdown-item\">Development Film\u00f3w<\/a>\t<li id=\"menu-item-3877\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3877 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/fundusze-filmowe-dofinansowania-na-film\/\" class=\" dropdown-item\">Fundusze, Dofinansowania, Dotacje<\/a>\t<li id=\"menu-item-3896\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3896 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/17\/dofinansowanie-pisf\/\" class=\" dropdown-item\">Dotacje PISF<\/a>\t<li id=\"menu-item-3898\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3898 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/fundusze-filmowe-dofinansowania-na-film\/sponsorzy\/\" class=\" dropdown-item\">Sponsorzy<\/a>\t<li id=\"menu-item-3875\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3875 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/produkcja\/\" class=\" dropdown-item\">Okres zdj\u0119ciowy<\/a>\t<li id=\"menu-item-3874\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3874 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/postprodukcja\/\" class=\" dropdown-item\">Postprodukcja<\/a>\t<li id=\"menu-item-3873\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3873 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/dystrybucja\/\" class=\" dropdown-item\">Dystrybucja<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-1779\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1779 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/blog-filmowy\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Blog<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-3894\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3894 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/21\/premiery-filmowe\/\" class=\" dropdown-item\">Premiery filmowe<\/a>\t<li id=\"menu-item-3895\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3895 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/17\/nagrody-i-festiwale-filmowe\/\" class=\" dropdown-item\">Nagrody i festiwale filmowe<\/a>\t<li id=\"menu-item-3891\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3891 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/07\/top-10-polskich-rezyserow\/\" class=\" dropdown-item\">TOP 10 polskich re\u017cyser\u00f3w<\/a>\t<li id=\"menu-item-3892\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3892 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/07\/top-10-polskich-aktorow\/\" class=\" dropdown-item\">TOP 10 polskich aktor\u00f3w<\/a>\t<li id=\"menu-item-3893\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3893 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/04\/27\/top-10-polskich-aktorek\/\" class=\" dropdown-item\">TOP 10 polskich aktorek<\/a>\t<li id=\"menu-item-3889\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3889 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/08\/top-10-polskich-operatorow-filmowych\/\" class=\" dropdown-item\">TOP 10 polskich operator\u00f3w filmowych<\/a>\t<li id=\"menu-item-3888\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3888 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/08\/top-10-polskich-producentow-filmowych-2\/\" class=\" dropdown-item\">TOP 10 polskich producent\u00f3w filmowych<\/a>\t<li id=\"menu-item-3890\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3890 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/07\/top-10-polskich-kompozytorow\/\" class=\" dropdown-item\">TOP 10 polskich kompozytor\u00f3w<\/a>\t<li id=\"menu-item-3887\" class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-3887 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/2023\/05\/08\/top-10-polskich-scenarzystow-filmowych\/\" class=\" dropdown-item\">TOP 10 polskich scenarzyst\u00f3w filmowych<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-1780\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1780 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/hollylodz.com\/index.php\/kontakt\/\" class=\"ekit-menu-nav-link\">Kontakt<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cfb060e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1cfb060e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e42b109\" data-id=\"1e42b109\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a3a04ce elementor-widget elementor-widget-heading\" data-id=\"2a3a04ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Poznaj kto wchodzi w sk\u0142ad ekipy filmowej<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0d8324 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b0d8324\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3d1c3c\" data-id=\"e3d1c3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e1006b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2e1006b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ekipa filmowa to zesp\u00f3\u0142 specjalist\u00f3w, kt\u00f3rzy pracuj\u0105 nad produkcj\u0105 filmow\u0105. W sk\u0142ad zespo\u0142u wchodz\u0105 m.in. re\u017cyser, scenarzysta, operator, monta\u017cysta, d\u017awi\u0119kowiec, scenograf, kostiumograf, charakteryzator, a tak\u017ce aktorzy i staty\u015bci.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-xga9h88 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"xga9h88\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9230439\" data-id=\"9230439\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-494b65d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"494b65d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Re\u017cyser jest osob\u0105 odpowiedzialn\u0105 za ca\u0142\u0105 produkcj\u0119 filmow\u0105. To on odpowiada za wyb\u00f3r obsady, planowanie scen, re\u017cyserowanie aktor\u00f3w i kierowanie ca\u0142\u0105 produkcj\u0105.<\/p><p>Scenarzysta jest osob\u0105 odpowiedzialn\u0105 za napisanie scenariusza. To on tworzy histori\u0119 i dialogi, kt\u00f3re zostan\u0105 p\u00f3\u017aniej zagrane przez aktor\u00f3w.<\/p><p>Operator filmowy jest odpowiedzialny za ustawienie kamery i rejestrowanie obrazu. To on decyduje o kadrze i o\u015bwietleniu.<\/p><p>Monta\u017cysta zajmuje si\u0119 monta\u017cem filmu. To on dobiera odpowiednie uj\u0119cia i uk\u0142ada je w logiczn\u0105 ca\u0142o\u015b\u0107.<\/p><p>D\u017awi\u0119kowiec zajmuje si\u0119 rejestracj\u0105 d\u017awi\u0119ku podczas kr\u0119cenia filmu oraz jego monta\u017cem.<\/p><p>Scenograf jest odpowiedzialny za zaprojektowanie i stworzenie scenografii, czyli wn\u0119trz i dekoracji, kt\u00f3re b\u0119d\u0105 widoczne na ekranie.<\/p><p>Kostiumograf zajmuje si\u0119 projektowaniem i tworzeniem kostium\u00f3w dla aktor\u00f3w.<\/p><p>Charakteryzator zajmuje si\u0119 makija\u017cem aktor\u00f3w i tworzeniem efekt\u00f3w specjalnych.<\/p><p>Aktorzy to osoby, kt\u00f3re odgrywaj\u0105 role w filmie. Staty\u015bci to osoby, kt\u00f3re pojawiaj\u0105 si\u0119 na planie filmowym w tle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6dd492b\" data-id=\"6dd492b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a07bd8d elementor-widget elementor-widget-image\" data-id=\"a07bd8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"1280\" src=\"https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/05\/filmstrip-camera-cinema-160562.png\" class=\"attachment-medium_large size-medium_large wp-image-3225\" alt=\"filmstrip, camera, cinema-160562.jpg\" srcset=\"https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/05\/filmstrip-camera-cinema-160562.png 640w, https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/05\/filmstrip-camera-cinema-160562-150x300.png 150w, https:\/\/hollylodz.com\/wp-content\/uploads\/2023\/05\/filmstrip-camera-cinema-160562-512x1024.png 512w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47bded1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"47bded1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-503e370\" data-id=\"503e370\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d85aa9e elementor-widget elementor-widget-text-editor\" data-id=\"d85aa9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wszyscy ci specjali\u015bci pracuj\u0105 razem, aby stworzy\u0107 film. Wsp\u00f3\u0142praca i koordynacja s\u0105 kluczowe w procesie produkcji filmowej. Ka\u017cdy z nich ma wa\u017cn\u0105 rol\u0119 do odegrania i jego praca jest niezb\u0119dna dla powodzenia ca\u0142ego projektu.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c2ed9ed elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5c2ed9ed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d5bd0b9\" data-id=\"1d5bd0b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24cafecb elementor-widget elementor-widget-heading\" data-id=\"24cafecb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Masz pytania?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-367fe52b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"367fe52b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zapraszamy do kontaktu<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78e98b86\" data-id=\"78e98b86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-316fb7ca wpr-button-icon-style-inline wpr-button-icon-position-right elementor-invisible elementor-widget elementor-widget-wpr-button\" data-id=\"316fb7ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"wpr-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t\t\n\t\t\n\t\t<div class=\"wpr-button-wrap elementor-clearfix\">\n\t\t<a class=\"wpr-button wpr-button-effect elementor-animation-grow\" data-text=\"\" href=\"https:\/\/hollylodz.com\/index.php\/kontakt\/\">\n\t\t\t\n\t\t\t<span class=\"wpr-button-content\">\n\t\t\t\t\t\t\t\t\t<span class=\"wpr-button-text\">Skontaktuj si\u0119<\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76f2098 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"76f2098\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8532a3f\" data-id=\"8532a3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25ab7da elementor-widget elementor-widget-elementskit-heading\" data-id=\"25ab7da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-text_center\"><p class=\"ekit-heading--title elementskit-section-title \">\u00a92023 HollyLodz.com<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e331428\" data-id=\"e331428\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48c9411 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-elementskit-page-list\" data-id=\"48c9411\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-page-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"elementor-icon-list-items  elementor-inline-items\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-050c974 ekit_badge_left\" href=\"https:\/\/hollylodz.com\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Strona g\u0142\u00f3wna<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-29e6080 ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/blog-filmowy\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Blog<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-5b06c44 ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/ekipy-filmowe\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Ekipy Filmowe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-2c96bcf ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/uslugi-filmowe\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Oferta<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-7739305 ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/kontakt\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Kontakt<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-64b7ccf ekit_badge_left\" href=\"https:\/\/hollylodz.com\/index.php\/mapastrony\/\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Mapa<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home Oferta Produkcja Ekipy Filmowe Blog Mapa Kontakt X Poznaj kto wchodzi w sk\u0142ad ekipy filmowej Ekipa filmowa to zesp\u00f3\u0142 specjalist\u00f3w, kt\u00f3rzy pracuj\u0105 nad produkcj\u0105 filmow\u0105. W sk\u0142ad zespo\u0142u wchodz\u0105 m.in. re\u017cyser, scenarzysta, operator, monta\u017cysta, d\u017awi\u0119kowiec, scenograf, kostiumograf, charakteryzator, a tak\u017ce aktorzy i staty\u015bci. Re\u017cyser jest osob\u0105 odpowiedzialn\u0105 za ca\u0142\u0105 produkcj\u0119 filmow\u0105. To on odpowiada za wyb\u00f3r obsady, planowanie scen, re\u017cyserowanie aktor\u00f3w i kierowanie ca\u0142\u0105 produkcj\u0105. Scenarzysta jest osob\u0105 odpowiedzialn\u0105 za napisanie scenariusza. To on tworzy histori\u0119 i dialogi, kt\u00f3re zostan\u0105 p\u00f3\u017aniej zagrane przez aktor\u00f3w. Operator filmowy jest odpowiedzialny za ustawienie kamery i rejestrowanie obrazu. To on decyduje o kadrze i o\u015bwietleniu. Monta\u017cysta zajmuje si\u0119 monta\u017cem filmu. To on dobiera odpowiednie uj\u0119cia i uk\u0142ada je w logiczn\u0105 ca\u0142o\u015b\u0107. D\u017awi\u0119kowiec zajmuje si\u0119 rejestracj\u0105 d\u017awi\u0119ku podczas kr\u0119cenia filmu oraz jego monta\u017cem. Scenograf jest odpowiedzialny za zaprojektowanie i stworzenie scenografii, czyli wn\u0119trz i dekoracji, kt\u00f3re b\u0119d\u0105 widoczne na ekranie. Kostiumograf zajmuje si\u0119 projektowaniem i tworzeniem kostium\u00f3w dla aktor\u00f3w. Charakteryzator zajmuje si\u0119 makija\u017cem aktor\u00f3w i tworzeniem efekt\u00f3w specjalnych. Aktorzy to osoby, kt\u00f3re odgrywaj\u0105 role w filmie. Staty\u015bci to osoby, kt\u00f3re pojawiaj\u0105 si\u0119 na planie filmowym w tle. Wszyscy ci specjali\u015bci pracuj\u0105 razem, aby stworzy\u0107 film. Wsp\u00f3\u0142praca i koordynacja s\u0105 kluczowe w procesie produkcji filmowej. Ka\u017cdy z nich ma wa\u017cn\u0105 rol\u0119 do odegrania i jego praca jest niezb\u0119dna dla powodzenia ca\u0142ego projektu. Masz pytania? Zapraszamy do kontaktu Skontaktuj si\u0119 \u00a92023 HollyLodz.com Strona g\u0142\u00f3wna Blog Ekipy Filmowe Oferta Kontakt Mapa<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_canvas","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2124","post","type-post","status-publish","format-standard","hentry","category-ekipa-filmowa"],"_links":{"self":[{"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/posts\/2124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/comments?post=2124"}],"version-history":[{"count":26,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/posts\/2124\/revisions"}],"predecessor-version":[{"id":3736,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/posts\/2124\/revisions\/3736"}],"wp:attachment":[{"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/media?parent=2124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/categories?post=2124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hollylodz.com\/index.php\/wp-json\/wp\/v2\/tags?post=2124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}